{"id":26334,"date":"2023-03-15T18:02:09","date_gmt":"2023-03-15T21:02:09","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=26334"},"modified":"2023-03-15T18:02:09","modified_gmt":"2023-03-15T21:02:09","slug":"michelin-empresa-mundial-abre-vagas-em-am-e-sp-confira","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/michelin-empresa-mundial-abre-vagas-em-am-e-sp-confira\/","title":{"rendered":"OPORTUNIDADE \u00daNICA: Michelin abre vagas, confira"},"content":{"rendered":"<p>A Michelin \u00e9 uma das maiores fabricantes de pneus em todo o mundo. Fundada em 1832, na Fran\u00e7a, a empresa ainda \u00e9 famosa pelo seu Guia Michelin, o qual conta com toda uma publica\u00e7\u00e3o tur\u00edstica que classifica os melhores hot\u00e9is e restaurantes ao redor do mundo, sendo considerado, inclusive, um case da empresa.<\/p>\n<p>Seu sucesso \u00e9 justificado por oferecer servi\u00e7os e produtos de qualidade \u00edmpar, sobretudo com um foco direcionado a combina\u00e7\u00e3o de mercadorias e pessoas. A empresa conta com uma gama de produtos em seu portf\u00f3lio, os quais incluem pneus espec\u00edficos, personalizados e direcionados para motocicletas, bicicletas, \u00f4nibus, tratores, caminh\u00f5es, avi\u00f5es, bicicletas e, inclusive, as naves especiais da NASA.<\/p>\n<p>Tudo isso aplicando tecnologia de ponta combinando ainda com sustentabilidade. Esse \u00faltimo, inclusive, uma das maiores estrat\u00e9gias e foco at\u00e9 o ano de 2030. Sempre focado no desenvolvimento, a empresa busca incorporar no seu ambiente de trabalho profissionais interessados em progredir dentro do mercado, al\u00e9m de caracter\u00edsticas gerais de um bom profissional, como responsabilidade, proatividade, disciplina e simpatia.<\/p>\n<p>Faz isso a fim de oferecer ao cliente um atendimento \u00edmpar e personalizado, al\u00e9m de qualidade, motivos pelo qual a empresa \u00e9 reconhecida e muito procurada no setor.<\/p>\n<p>A empresa conta ainda com postos de trabalho distribu\u00eddos em todo o pa\u00eds e, por estar em crescimento constante, com frequ\u00eancia divulga <a href=\"https:\/\/99empregos.com.br\/panasonic-empresa-abre-vagas-de-emprego-em-mg-e-sp-confira\/\" target=\"_blank\" rel=\"noopener\">vagas<\/a> de trabalho. Confira as<a href=\"https:\/\/99empregos.com.br\/vaga\/tim-empresa-abre-vagas-de-emprego-em-todos-os-estados-veja\/\" target=\"_blank\" rel=\"noopener\"> oportunidades<\/a> que est\u00e3o abertas atualmente:<\/p>\n<ul>\n<li>Serralheiro &#8211; Manaus\/AM<\/li>\n<li>Est\u00e1gio em Engenharia de Produ\u00e7\u00e3o &#8211; Guarulhos\/SP<\/li>\n<li>Operador de Produ\u00e7\u00e3o &#8211; Banco de Talentos &#8211; Manaus\/AM<\/li>\n<li>Analista de Treinamento e Desenvolvimento &#8211; Brasil<\/li>\n<li>Eletricista de Manuten\u00e7\u00e3o Industrial &#8211; Guarulhos\/SP<\/li>\n<li>Operador de Produ\u00e7\u00e3o &#8211; Itatiaia\/SP<\/li>\n<\/ul>\n<h2>Saiba mais sobre a Michelin<\/h2>\n<p>A empresa \u00e9 ainda conhecida por oferecer plano de carreira, isto \u00e9, d\u00e1 a possibilidade de crescimento aos seus colaboradores. Al\u00e9m de oferecer um sal\u00e1rio compat\u00edvel com o mercado de trabalho, o colaborador pode contar com os seguintes benef\u00edcios: vale-transporte, vale-refei\u00e7\u00e3o, seguro de vida, assist\u00eancia m\u00e9dica, assist\u00eancia odontol\u00f3gica.<\/p>\n<h2>Saiba como concorrer as vagas dispon\u00edveis<\/h2>\n<p>O processo para se candidatar as vagas da Michelin \u00e9 simples, ao clicar nesse<a href=\"https:\/\/99empregos.com.br\/vaga\/michelin-empresa-mundial-abre-vagas-em-am-e-sp-confira\/\" target=\"_blank\" rel=\"noopener\"> link<\/a>, voc\u00ea poder\u00e1 clicar em Candidatar que voc\u00ea ser\u00e1 redirecionado para a \u00e1rea Trabalhe Conosco da empresa. L\u00e1, voc\u00ea ter\u00e1 acesso as diversas vagas e, ao escolher a que se encaixa no seu perfil clique em: Ver descri\u00e7\u00e3o da vaga.<\/p>\n<p>Em seguida, certifique-se de preencher os pr\u00e9-requisitos. Depois \u00e9 s\u00f3 clicar em Inscreva-se e anexar o seu curr\u00edculo. Voc\u00ea pode ainda cadastrar o seu curr\u00edculo no banco de vagas caso n\u00e3o encontre uma vaga adequada para seu perfil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Michelin \u00e9 uma das maiores fabricantes de pneus em todo o mundo. Fundada em 1832, na Fran\u00e7a, a empresa ainda \u00e9 famosa pelo seu Guia Michelin, o qual conta com toda uma publica\u00e7\u00e3o tur\u00edstica que classifica os melhores hot\u00e9is e restaurantes ao redor do mundo, sendo considerado, inclusive, um case da empresa. Seu sucesso [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[2698,1401,1402],"class_list":["post-26334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas","tag-nivel-fundamental","tag-nivel-medio","tag-nivel-superior"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26334"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/26341"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}