{"id":26402,"date":"2023-03-16T11:27:16","date_gmt":"2023-03-16T14:27:16","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=26402"},"modified":"2023-03-16T11:27:16","modified_gmt":"2023-03-16T14:27:16","slug":"alianca-metalurgica-confira-as-vagas-para-o-estado-de-sao-paulo","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/alianca-metalurgica-confira-as-vagas-para-o-estado-de-sao-paulo\/","title":{"rendered":"Alian\u00e7a Metal\u00fargica: Empresa tem vagas com \u00f3timos sal\u00e1rios, veja"},"content":{"rendered":"<p>A Alian\u00e7a Metal\u00fargica \u00e9 uma das mais tradicionais e reconhecidas fabricantes de fechaduras, ferragens, reguladores para g\u00e1s e rod\u00edzios. Com atendimento focado na constru\u00e7\u00e3o civil e, nela, nos seus mais diferentes segmentos, o cat\u00e1logo da empresa conta ainda com mais de 1000 itens exclusivos e personalizados, tudo isso criado ao longo dos seus 90 anos de exist\u00eancia.<\/p>\n<p>A empresa tem sua f\u00e1brica centralizada, desde 1949, em S\u00e3o Paulo. A combina\u00e7\u00e3o de excelente mat\u00e9ria prima, tecnologia de ponta e qualidade \u00edmpar, fazem da empresa refer\u00eancia no \u00e2mbito da constru\u00e7\u00e3o civil.\u00a0 Assim, seu alcance \u00e9 enorme, tanto nacionalmente quanto internacionalmente.<\/p>\n<p>Para atender a toda a demanda de produ\u00e7\u00e3o, entrega e servi\u00e7os personalizados, a empresa conta, atualmente, com cerca de 700 colaboradores e in\u00fameros representantes divididos em todas as regi\u00f5es do pa\u00eds e mundo.<\/p>\n<p>Com o prop\u00f3sito de melhorar e facilitar a vida das pessoas, assim como com o objetivo de se perdurar como refer\u00eancia no mercado, a empresa busca profissionais que se integram com os valores base da empresa e que est\u00e3o em busca de crescimento e desenvolvimento constante.<\/p>\n<p>Assim, oferece, com frequ\u00eancia, <a href=\"https:\/\/99empregos.com.br\/tim-empresa-abre-vagas-de-emprego-em-todos-os-estados-veja\/\" target=\"_blank\" rel=\"noopener\">vagas<\/a> de trabalho em diversas regi\u00f5es do pa\u00eds que abrange diversos n\u00edveis de escolaridade, experi\u00eancias e perfis. Confira algumas <a href=\"https:\/\/99empregos.com.br\/vivo-marca-de-telefonia-abre-vagas-em-todos-os-estados-veja\/\" target=\"_blank\" rel=\"noopener\">vagas<\/a> dispon\u00edveis:<\/p>\n<ul>\n<li>Consultor de Vendas Internas &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Retificador &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Consultor de Vendas Interno &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Assistente de E-commerce &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Assistente de Intelig\u00eancia de Mercado &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Especialista FP&amp;A &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Auxiliar de Produ\u00e7\u00e3o &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Eletricista Industrial &#8211; S\u00e3o Paulo\/SP<\/li>\n<\/ul>\n<h2 class=\"about-us-text\">Saiba mais sobre a Alian\u00e7a Metal\u00fargica<\/h2>\n<p>A empresa \u00e9 ainda conhecida por oferecer plano de carreira, isto \u00e9, d\u00e1 a possibilidade de crescimento aos seus colaboradores. Al\u00e9m de oferecer um sal\u00e1rio compat\u00edvel com o mercado de trabalho, o colaborador pode contar com os seguintes benef\u00edcios: massoterapia,\u00a0 vale-transporte, refeit\u00f3rio, seguro de vida, assist\u00eancia m\u00e9dica, assist\u00eancia odontol\u00f3gica, gin\u00e1stica laboral e cesta b\u00e1sica.<\/p>\n<div class=\"about-icons-div col-md-3 col-xs-12\">\n<h2 class=\"about-icons-img-div\">Saiba como concorrer as vagas dispon\u00edveis<\/h2>\n<\/div>\n<div><\/div>\n<div>\n<p>O processo para se candidatar as vagas da Alian\u00e7a Metal\u00fargica \u00e9 simples, ao clicar nesse <a href=\"https:\/\/99empregos.com.br\/vaga\/alianca-metalurgica-confira-as-vagas-para-o-estado-de-sao-paulo\/\" target=\"_blank\" rel=\"noopener\">link<\/a>, voc\u00ea poder\u00e1 clicar em Candidatar que voc\u00ea ser\u00e1 redirecionado para a \u00e1rea Trabalhe Conosco da empresa. L\u00e1, voc\u00ea ter\u00e1 acesso as diversas vagas e, ao escolher a que se encaixa no seu perfil clique em: Ver descri\u00e7\u00e3o da vaga.<\/p>\n<p>Em seguida, certifique-se de preencher os pr\u00e9-requisitos. Depois \u00e9 s\u00f3 clicar em Inscreva-se e anexar o seu curr\u00edculo. Voc\u00ea pode ainda cadastrar o seu curr\u00edculo no banco de vagas caso n\u00e3o encontre uma vaga adequada para seu perfil.<\/p>\n<\/div>\n<div class=\"about-icons-div col-md-3 col-xs-12\">\n<h3 class=\"about-us-icons-tile\"><\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Alian\u00e7a Metal\u00fargica \u00e9 uma das mais tradicionais e reconhecidas fabricantes de fechaduras, ferragens, reguladores para g\u00e1s e rod\u00edzios. Com atendimento focado na constru\u00e7\u00e3o civil e, nela, nos seus mais diferentes segmentos, o cat\u00e1logo da empresa conta ainda com mais de 1000 itens exclusivos e personalizados, tudo isso criado ao longo dos seus 90 anos [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[2698,1401,1402],"class_list":["post-26402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas","tag-nivel-fundamental","tag-nivel-medio","tag-nivel-superior"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26402"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/26405"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}