{"id":26456,"date":"2023-03-16T16:42:57","date_gmt":"2023-03-16T19:42:57","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=26456"},"modified":"2023-03-16T16:42:57","modified_gmt":"2023-03-16T19:42:57","slug":"granado-empresa-tem-33-vagas-de-emprego-com-entrada-urgente","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/granado-empresa-tem-33-vagas-de-emprego-com-entrada-urgente\/","title":{"rendered":"Granado: Empresa tem 33 vagas de emprego com entrada urgente"},"content":{"rendered":"<p>A Granado \u00e9 uma das empresas de cosm\u00e9ticos e medicamentos mais tradicionais do Brasil. A empresa foi fundada no Rio de Janeiro em 1870 por um portugu\u00eas botic\u00e1rio que tinha um amplo conhecimento sobre plantar e ervas medicinais, as quais, inclusive, s\u00e3o a base, at\u00e9 hoje, do desenvolvimento dos principais produtos da Granado.<\/p>\n<p>A empresa \u00e9, ainda, refer\u00eancia mundial no cen\u00e1rio de cosm\u00e9ticos, j\u00e1 que tem como um dos seus valores irrefut\u00e1veis a responsabilidade socioambiental. Partindo desse principio, coleciona alguns pioneirismos, como foi a primeira empresa a banir o parabeno dos seus produtos depois de descobrirem o qu\u00e3o t\u00f3xico \u00e9 a subst\u00e2ncia e, tamb\u00e9m, o primeiro a usar gordura vegetal para a fabrica\u00e7\u00e3o de sabonetes. Al\u00e9m disso, a empresa n\u00e3o faz teste dos seus produtos em animais e, ainda, garantem que suas embalagens sejam recicladas como um todo.<\/p>\n<p>O impacto positivo da Granado \u00e9 vis\u00edvel tanto no setor ambiental quanto na ind\u00fastria de cosm\u00e9ticos pela qualidade \u00edmpar dos seus produtos, assim como pela funcionalidade desses. Nesse sentido, \u00e9 poss\u00edvel medir esse sucesso atrav\u00e9s das mais de 80 lojas da Granado distribu\u00eddas em todo o pa\u00eds.<\/p>\n<p>Al\u00e9m dessas, a marca ganha relev\u00e2ncia nacional e j\u00e1 possui tr\u00eas lojas em Paris, local considerado a capital dos perfumes. E, ainda, o site atende todo o exterior, tendo os EUA como um dos principais consumidores da ampla e diversa cartela de produtos da Granado.<\/p>\n<p>Para atender a ampla demanda de produtos, a empresa recruta, com frequ\u00eancia <a href=\"https:\/\/99empregos.com.br\/vivo-marca-de-telefonia-abre-vagas-em-todos-os-estados-veja\/\" target=\"_blank\" rel=\"noopener\">funcion\u00e1rios<\/a> para diversos setores e de diversos n\u00edveis de escolaridade. Confira algumas das 33 <a href=\"https:\/\/99empregos.com.br\/tim-empresa-abre-vagas-de-emprego-em-todos-os-estados-veja\/\" target=\"_blank\" rel=\"noopener\">vagas<\/a> dispon\u00edveis:<\/p>\n<ul>\n<li>Assistente de Design &#8211; Rio de Janeiro\/RJ<\/li>\n<li>Coordenador de RH &#8211; varejo &#8211; Rio de Janeiro\/RJ<\/li>\n<li>Analista de marketing Jr. &#8211; Rio de Janeiro\/RJ<\/li>\n<li>Vendedor &#8211; Curitiba\/PR<\/li>\n<li>Gerente de Loja em Shopping &#8211; Curitiba\/PR<\/li>\n<li>Gerente de Loja &#8211; Goi\u00e2nia\/GO<\/li>\n<li>L\u00edder de Atendimento &#8211; Manaus\/AM<\/li>\n<li>Supervisor de Seguran\u00e7a de Trabalho &#8211; Brasil<\/li>\n<li>Auxiliar de Loja &#8211; S\u00e3o Paulo\/SP<\/li>\n<li>Analista de Valida\u00e7\u00e3o Pleno &#8211; Rio de Janeiro<\/li>\n<li>L\u00edder de Atendimento &#8211; Shopping &#8211; Campo Grande\/PR<\/li>\n<\/ul>\n<h2>Saiba mais sobre a Granado<\/h2>\n<p>A empresa oferece um sal\u00e1rio compat\u00edvel com o mercado de trabalho. Al\u00e9m disso, o colaborador pode contar com os seguintes benef\u00edcios: vale-transporte, vale-refei\u00e7\u00e3o, seguro de vida, assist\u00eancia m\u00e9dica, assist\u00eancia odontol\u00f3gica e tamb\u00e9m participa\u00e7\u00e3o no lucro ou resultados da empresa.<\/p>\n<h2>Saiba como concorrer as vagas dispon\u00edveis<\/h2>\n<p>O processo para se candidatar as vagas da Granado \u00e9 simples, ao clicar nesse <a href=\"https:\/\/99empregos.com.br\/vaga\/granado-empresa-tem-33-vagas-de-emprego-com-entrada-urgente\/\" target=\"_blank\" rel=\"noopener\">link,<\/a> voc\u00ea poder\u00e1 clicar em Candidatar que voc\u00ea ser\u00e1 redirecionado para a \u00e1rea Trabalhe Conosco da empresa. L\u00e1, voc\u00ea ter\u00e1 acesso as diversas vagas e, ao escolher a que se encaixa no seu perfil clique em: Ver descri\u00e7\u00e3o da vaga.<\/p>\n<p>Em seguida, certifique-se de preencher os pr\u00e9-requisitos. Depois \u00e9 s\u00f3 clicar em Inscreva-se e anexar o seu curr\u00edculo. Voc\u00ea pode ainda cadastrar o seu curr\u00edculo no banco de vagas caso n\u00e3o encontre uma vaga adequada para seu perfil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Granado \u00e9 uma das empresas de cosm\u00e9ticos e medicamentos mais tradicionais do Brasil. A empresa foi fundada no Rio de Janeiro em 1870 por um portugu\u00eas botic\u00e1rio que tinha um amplo conhecimento sobre plantar e ervas medicinais, as quais, inclusive, s\u00e3o a base, at\u00e9 hoje, do desenvolvimento dos principais produtos da Granado. A empresa [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26462,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1401,1402,2683],"class_list":["post-26456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas","tag-nivel-medio","tag-nivel-superior","tag-nivel-tecnico"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26456"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/26462"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}