{"id":26509,"date":"2023-03-16T18:13:42","date_gmt":"2023-03-16T21:13:42","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=26509"},"modified":"2025-04-30T15:26:06","modified_gmt":"2025-04-30T18:26:06","slug":"startup-do-setor-automotivo-abre-novas-vagas-de-emprego-confira","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/startup-do-setor-automotivo-abre-novas-vagas-de-emprego-confira\/","title":{"rendered":"Startup do setor automotivo abre novas vagas de emprego, confira"},"content":{"rendered":"<p>A Webmotors, startup de compra e venda de ve\u00edculos com mais de 27 anos de experi\u00eancia no mercado brasileiro, est\u00e1 com <a href=\"https:\/\/99empregos.com.br\/vaga\/leo-madeiras-anuncia-vagas-de-emprego-em-sao-paulo-e-rio-de-janeiro\/\">novas vagas de emprego<\/a> abertas na cidade de S\u00e3o Paulo (SP) e de forma remota. Expandindo cada vez mais seus investimentos no setor, a companhia agora precisa dos seguintes profissionais:<\/p>\n<ul>\n<li><span style=\"font-weight: 400\">Agente de Atendimento;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Analista de Opera\u00e7\u00f5es Junior (Foco em Metodologias de Qualidade &#8211; Lean Manufacturing e Six Sigma);\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Analista de Qualidade S\u00e3o Paulo &#8211; SP e Remoto;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Analista de Seguran\u00e7a da Informa\u00e7\u00e3o S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Analista S\u00eanior de Dados MKT S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Analista S\u00eanior de Marketing (Branding) S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Coordenador(a) de TI Efetivo Coordenador(a) de TI &#8211; Infra &#8211; Sec &#8211; Cloud S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Coordenador de Suporte &#8211; N2;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Desenvolvedor back-end PL Trabalho Remoto;<\/span><\/li>\n<li><span style=\"font-weight: 400\">Desenvolvedor Back-End S\u00eanior S\u00e3o Paulo &#8211; SP e Remoto;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Desenvolvedor Front-End Pleno S\u00e3o Paulo &#8211; SP e Remoto;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Desenvolvedor Front-end S\u00eanior Trabalho Remoto;<\/span><\/li>\n<li><span style=\"font-weight: 400\">Engenheiro(a) de Dados Pleno S\u00e3o Paulo &#8211; SP e Remoto;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Engenheiro(a) de Dados S\u00eanior S\u00e3o Paulo &#8211; SP e Remoto;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Est\u00e1gio em Marketing &#8211; CRM S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Est\u00e1gio em Marketing\/M\u00eddia S\u00e3o Paulo &#8211; SP;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Executivo de Contas PL Efetivo Gerente Especialista II (Belo Horizonte) Contagem &#8211; MG;\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400\">Gerente Especialista II Jundia\u00ed.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_26511\" aria-describedby=\"caption-attachment-26511\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-26511\" src=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/03\/webmotors-vagas-2023.jpg\" alt=\"Webmotors est\u00e1 com novas vagas de emprego, confira as oportunidades e saiba como se candidatar. Foto: Divulga\u00e7\u00e3o\" width=\"1200\" height=\"650\" srcset=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/03\/webmotors-vagas-2023.jpg 1200w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/03\/webmotors-vagas-2023-300x163.jpg 300w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/03\/webmotors-vagas-2023-1024x555.jpg 1024w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/03\/webmotors-vagas-2023-768x416.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-26511\" class=\"wp-caption-text\">Webmotors est\u00e1 com novas vagas de emprego, confira as oportunidades e saiba como se candidatar. Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<h3>Mais informa\u00e7\u00f5es sobre a Webmotors<\/h3>\n<p>Aqui na Webmotors respeito e inclus\u00e3o fazem parte dos nossos itens de s\u00e9rie. Acreditamos que as diferen\u00e7as somam e por isso, diversidade \u00e9 um de nossos pilares. Ent\u00e3o, candidaturas de pessoas pretas, mulheres, PCD, LGBTQIA+ e melhoridade s\u00e3o muito bem-vindas! Estamos h\u00e1 27 anos na estrada e fomos a primeira startup brasileira a inovar na forma de comprar e vender carros e motos. Nesses anos, n\u00e3o paramos de acelerar e evolu\u00edmos para muuuuito al\u00e9m dos classificados!<\/p>\n<p>Contamos com acionistas super estrat\u00e9gicos e robustos, o Grupo Santander e australiana Car Sales, e juntos criamos um ecossistema de solu\u00e7\u00f5es, uma vez que queremos estar com os nossos clientes ao longo da sua jornada de compra, venda e uso de ve\u00edculos. Hoje somos l\u00edderes de mercado e o ecossistema mais completo do segmento! Mas fica tranquilo, porque o que n\u00e3o falta \u00e9 combust\u00edvel para acelerar ainda mais. Com uma vis\u00e3o consolidada, n\u00f3s queremos ganhar o mundo (e j\u00e1 estamos acelerando nesse percurso).<\/p>\n<h3>Como se candidatar \u00e0s vagas de emprego<\/h3>\n<p>Se voc\u00ea encontrou uma oportunidade de emprego que se encaixa com o seu perfil profissional, <a href=\"https:\/\/99empregos.com.br\/vaga\/webmotors-abre-novas-vagas-de-emprego-confira-as-oportunidades\/\">basta clicar neste link<\/a> para se candidatar agora mesmo por l\u00e1. No entanto, antes de efetivar a sua inscri\u00e7\u00e3o, recomendamos que fa\u00e7a uma revis\u00e3o completa de todos os pr\u00e9-requisitos solicitados pela companhia. Boa sorte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Webmotors, startup de compra e venda de ve\u00edculos com mais de 27 anos de experi\u00eancia no mercado brasileiro, est\u00e1 com novas vagas de emprego abertas na cidade de S\u00e3o Paulo (SP) e de forma remota. Expandindo cada vez mais seus investimentos no setor, a companhia agora precisa dos seguintes profissionais: Agente de Atendimento;\u00a0 Analista [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":26512,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[5,778,1542],"class_list":["post-26509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-empregos","tag-novas-oportunidades","tag-vagas-2023"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26509"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/26509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/26512"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}