{"id":36292,"date":"2023-05-30T11:09:02","date_gmt":"2023-05-30T14:09:02","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=36292"},"modified":"2025-04-30T16:08:44","modified_gmt":"2025-04-30T19:08:44","slug":"sua-vaga-espera-por-voce-hoje-verisure-brasil-contrata-agora-mesmo-envie-o-curriculo","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/sua-vaga-espera-por-voce-hoje-verisure-brasil-contrata-agora-mesmo-envie-o-curriculo\/","title":{"rendered":"SUA VAGA ESPERA POR VOC\u00ca HOJE: Verisure Brasil contrata agora mesmo, envie o curr\u00edculo!"},"content":{"rendered":"<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-[#444654]\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-xl xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Que tal trabalhar com o setor de seguran\u00e7a residencial e empresarial? A <a href=\"https:\/\/www.verisure.com.br\/\" target=\"_blank\" rel=\"noopener\">Verisure Brasil<\/a> divulgou recentemente novas vagas de emprego abertas em sua equipe. Seja voc\u00ea um especialista em vendas, instala\u00e7\u00e3o ou monitoramento, a companhia tem tudo para te oferecer \u00f3timas oportunidades no mercado. N\u00e3o perca essa oportunidade de fazer parte de uma empresa l\u00edder no setor e confira abaixo quais s\u00e3o as vagas e suas respectivas localiza\u00e7\u00f5es:<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Analista de Remunera\u00e7\u00e3o Pleno &#8211; S\u00e3o Paulo &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Analista Tribut\u00e1rio J\u00fanior &#8211; S\u00e3o Paulo &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Analista de Treinamento de Vendas Pl &#8211; S\u00e3o Paulo &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Campinas &#8211; SP, Ribeir\u00e3o Preto &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Operador de Contact Center (Visitas) &#8211; S\u00e3o Paulo &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Ribeir\u00e3o Preto &#8211; SP, Campinas &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Campinas &#8211; SP, Campinas &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; S\u00e3o Jos\u00e9 dos Campos &#8211; SP, S\u00e3o Caetano do Sul &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Vit\u00f3ria &#8211; ES, Vit\u00f3ria &#8211; ES;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Rio de Janeiro &#8211; Petr\u00f3polis &#8211; RJ, Petr\u00f3polis &#8211; RJ;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Rio de Janeiro &#8211; Cabo Frio &#8211; RJ, Cabo Frio &#8211; RJ;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Rio de Janeiro &#8211; Niter\u00f3i &#8211; RJ, Niter\u00f3i &#8211; RJ;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendedor Externo &#8211; Rio de Janeiro &#8211; Barra da Tijuca &#8211; RJ, Rio de Janeiro &#8211; RJ;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Vendas Externa &#8211; S\u00e3o Paulo &#8211; SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Consultor de Vendas &#8211; S\u00e3o Paulo &#8211; SP.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_36294\" aria-describedby=\"caption-attachment-36294\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-36294\" src=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/05\/verisure-vagas-2023.jpg\" alt=\"Quer trabalhar hoje? Confira quais s\u00e3o as vagas de emprego abertas na Verisure Brasil e candidate-se agora mesmo. Foto: Reprodu\u00e7\u00e3o\/ Twitter\" width=\"1200\" height=\"650\" srcset=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/05\/verisure-vagas-2023.jpg 1200w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/05\/verisure-vagas-2023-300x163.jpg 300w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/05\/verisure-vagas-2023-1024x555.jpg 1024w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/05\/verisure-vagas-2023-768x416.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-36294\" class=\"wp-caption-text\">Quer trabalhar hoje? Confira quais s\u00e3o as vagas de emprego abertas na Verisure Brasil e candidate-se agora mesmo. Foto: Reprodu\u00e7\u00e3o\/ Twitter<\/figcaption><\/figure>\n<h3>Mais informa\u00e7\u00f5es sobre a Verisure Brasil<\/h3>\n<p>A Verisure est\u00e1 em constante crescimento. Com mais de 30 anos de experi\u00eancia, estamos presentes em 16 pa\u00edses (Su\u00e9cia, Noruega, Dinamarca, Finl\u00e2ndia, B\u00e9lgica, Alemanha, Holanda, Reino Unido, Espanha, Fran\u00e7a, Portugal, It\u00e1lia, Chile, Brasil, Argentina e Peru). O grupo possui mais de 16.000 funcion\u00e1rios, que atendem mais de 3 milh\u00f5es de clientes, \u00e9 l\u00edder na Europa e est\u00e1 crescendo rapidamente na Am\u00e9rica do Sul.<\/p>\n<h3>Como se candidatar?<\/h3>\n<p>Se voc\u00ea encontrou uma oportunidade de emprego que se encaixa com o seu perfil profissional, \u00e9 s\u00f3 <strong><a href=\"https:\/\/99empregos.com.br\/vaga\/verisure-brasil-contrata-veja-as-vagas-e-candidate-se-em-5-minutos\/\">CLICAR NESTE LINK AQUI<\/a> <\/strong>para se candidatar agora mesmo e enviar o seu curr\u00edculo. No entanto, antes de efetivar a sua inscri\u00e7\u00e3o, recomendamos que sempre revise todos os pr\u00e9-requisitos solicitados por l\u00e1. A equipe do 123 Empregos te deseja uma boa sorte!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Que tal trabalhar com o setor de seguran\u00e7a residencial e empresarial? A Verisure Brasil divulgou recentemente novas vagas de emprego abertas em sua equipe. Seja voc\u00ea um especialista em vendas, instala\u00e7\u00e3o ou monitoramento, a companhia tem tudo para te oferecer \u00f3timas oportunidades no mercado. N\u00e3o perca essa oportunidade de fazer parte de uma empresa l\u00edder [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":36295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1544,2500,16],"class_list":["post-36292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-1544","tag-empregos-hoje","tag-vagas-de-emprego"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=36292"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/36295"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=36292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=36292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=36292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}