{"id":36959,"date":"2023-06-05T12:00:31","date_gmt":"2023-06-05T15:00:31","guid":{"rendered":"https:\/\/123empregos.com.br\/?p=36959"},"modified":"2023-06-05T12:00:31","modified_gmt":"2023-06-05T15:00:31","slug":"sua-chance-de-trabalhar-hoje-05-06-teknisa-abre-novas-vagas-de-emprego-confira","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/sua-chance-de-trabalhar-hoje-05-06-teknisa-abre-novas-vagas-de-emprego-confira\/","title":{"rendered":"SUA CHANCE DE TRABALHAR HOJE (05\/06): Teknisa abre novas vagas de emprego, confira!"},"content":{"rendered":"<p>A Teknisa, renomada empresa de tecnologia e software, anunciou recentemente a abertura de <a href=\"https:\/\/99empregos.com.br\/vaga\/dufrio-divulgou-mais-de-50-vagas-de-emprego-pelo-brasil\/\">novas vagas de emprego<\/a> em sua equipe. Com expertise no desenvolvimento de solu\u00e7\u00f5es inovadoras para o setor de servi\u00e7os e atendimento ao cliente, a companhia busca profissionais qualificados e apaixonados por tecnologia para integrarem sua equipe. Confira abaixo todas as oportunidades dispon\u00edveis atualmente por l\u00e1:<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Analista de Administra\u00e7\u00e3o de Redes &#8211; Belo Horizonte, MG e Remoto;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Analista de Teste Jr &#8211; BH\/MG &#8211; Belo Horizonte, MG;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assistente de Prospec\u00e7\u00e3o SDR\u00a0 &#8211; Nova Lima, MG;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assistente de Suporte ERP &#8211; BH\/MG &#8211; Belo Horizonte, MG;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assistente de Suporte PDV &#8211; Plantonista &#8211; BH\/MG &#8211; Belo Horizonte, MG;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Banco de Talentos &#8211; Exclusivo PCD &#8211; BH\/MG &#8211; Belo Horizonte, MG;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Consultor de Implanta\u00e7\u00e3o &#8211; ERP Cont\u00e1bil\/Fiscal &#8211; SP\/SP &#8211; S\u00e3o Paulo, SP;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Consultor de Implanta\u00e7\u00e3o &#8211; Tecfood (SP) &#8211; S\u00e3o Paulo, SP e Remoto;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Estagi\u00e1rio de Prospec\u00e7\u00e3o SDR &#8211; Vila da Serra &#8211; Nova Lima, MG.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_36961\" aria-describedby=\"caption-attachment-36961\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-36961\" src=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/06\/teknisa-vagas-2023.jpg\" alt=\"Sua chance de trabalhar AINDA HOJE: Teknisa abre novas vagas, confira as oportunidades. Foto: Reprodu\u00e7\u00e3o\/ Web\" width=\"1200\" height=\"650\" srcset=\"https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/06\/teknisa-vagas-2023.jpg 1200w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/06\/teknisa-vagas-2023-300x163.jpg 300w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/06\/teknisa-vagas-2023-1024x555.jpg 1024w, https:\/\/99empregos.com.br\/blog\/wp-content\/uploads\/2023\/06\/teknisa-vagas-2023-768x416.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-36961\" class=\"wp-caption-text\">Sua chance de trabalhar AINDA HOJE: Teknisa abre novas vagas, confira as oportunidades. Foto: Reprodu\u00e7\u00e3o\/ Web<\/figcaption><\/figure>\n<h3>Mais informa\u00e7\u00f5es sobre a Teknisa<\/h3>\n<p>Somos uma uma empresa com mais de 32 anos de atua\u00e7\u00e3o no mercado, com clientes em toda a Am\u00e9rica Latina e nos mais diferentes segmentos, desde gest\u00e3o de pessoas, ind\u00fastrias de cosm\u00e9ticos, gest\u00e3o de com\u00e9rcios e indo at\u00e9 nosso principal nicho, que \u00e9 a alimenta\u00e7\u00e3o industrial. Somos especializados no segmento de food service e temos certeza que pelo menos uma vez na vida, voc\u00ea j\u00e1 foi cliente do nosso cliente. Afinal, hoje em dia marcamos presen\u00e7a em no m\u00ednimo duas lojas a cada shopping do pa\u00eds inteiro.<\/p>\n<h3>Como se candidatar?<\/h3>\n<p>Se voc\u00ea encontrou uma oportunidade de emprego que se encaixa com o seu perfil profissional, basta <strong><a href=\"https:\/\/99empregos.com.br\/vaga\/teknisa-abre-novas-vagas-de-emprego-confira-as-oportunidades\/\">CLICAR AQUI NESTE LINK<\/a><\/strong> para se candidatar agora mesmo por l\u00e1. No entanto, antes de efetivar a sua inscri\u00e7\u00e3o, recomendamos que fa\u00e7a uma revis\u00e3o completa e detalhada de todos os pr\u00e9-requisitos solicitados pela companhia. A equipe do 123 Empregos te deseja uma boa sorte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Teknisa, renomada empresa de tecnologia e software, anunciou recentemente a abertura de novas vagas de emprego em sua equipe. Com expertise no desenvolvimento de solu\u00e7\u00f5es inovadoras para o setor de servi\u00e7os e atendimento ao cliente, a companhia busca profissionais qualificados e apaixonados por tecnologia para integrarem sua equipe. Confira abaixo todas as oportunidades dispon\u00edveis [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":36962,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[5,2500,2582,1542],"class_list":["post-36959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-empregos","tag-empregos-hoje","tag-novas-oportunidades-de-emprego","tag-vagas-2023"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=36959"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/36959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/36962"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=36959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=36959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=36959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}