{"id":60110,"date":"2024-07-04T18:14:09","date_gmt":"2024-07-04T21:14:09","guid":{"rendered":"https:\/\/123empregos.com.br\/blog\/?p=60110"},"modified":"2024-07-04T18:14:09","modified_gmt":"2024-07-04T21:14:09","slug":"ferroport-empresa-de-alta-relevancia-no-segmento-industrial-tem-vagas-confira","status":"publish","type":"post","link":"https:\/\/99empregos.com.br\/blog\/ferroport-empresa-de-alta-relevancia-no-segmento-industrial-tem-vagas-confira\/","title":{"rendered":"Ferroport: Empresa de ALTA relev\u00e2ncia no segmento industrial tem vagas, confira"},"content":{"rendered":"<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-31\" data-scroll-anchor=\"false\">\n<div class=\"py-2 juice:py-[18px] px-3 text-base md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-3 text-base juice:gap-4 juice:md:gap-5 juice:lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-3\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"e3123fd2-7086-4181-ac0e-6dd0bb399d14\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>A Ferroport \u00e9 uma parceria 100% brasileira formada pela mineradora Anglo American e pela empresa de infraestrutura e log\u00edstica Prumo Log\u00edstica. Seu principal foco \u00e9 a opera\u00e7\u00e3o do terminal portu\u00e1rio de min\u00e9rio de ferro no Porto do A\u00e7u.<\/p>\n<p>Com uma equipe diversificada e altamente especializada, a empresa possui ampla experi\u00eancia em terminais portu\u00e1rios e utiliza tecnologia de ponta, elementos essenciais para a constru\u00e7\u00e3o de uma identidade robusta.<\/p>\n<p>A Ferroport tamb\u00e9m se dedica \u00e0 efici\u00eancia operacional e \u00e0 implementa\u00e7\u00e3o de solu\u00e7\u00f5es eficazes no mercado, sempre com respeito ao meio ambiente e \u00e0s rela\u00e7\u00f5es humanas, garantindo a seguran\u00e7a de seus colaboradores, parceiros e comunidades circundantes.<\/p>\n<p>Dessa forma, a empresa desenvolve projetos baseados na execu\u00e7\u00e3o segura e sustent\u00e1vel, visando proporcionar excel\u00eancia com custos e impactos reduzidos para todos os envolvidos.<\/p>\n<p>Assim, busca, constantemente, colaboradores para integrar a equipe. Equipe essa que atua em um ambiente onde h\u00e1 a possibilidade de ascens\u00e3o e desenvolvimento profissional de maneira constante e que oferece uma gama de oportunidades. O time da empresa \u00e9 ainda marcado pela diversidade, uma vez que a rede acredita que cada colaborador tem alto poder de agregar valor a empresa como um todo.<\/p>\n<p>Com um crescimento significativo no setor de minera\u00e7\u00e3o, a Ferroport frequentemente abre <a href=\"https:\/\/99empregos.com.br\/blog\/grupo-souza-lima-empresa-tem-mais-de-274-vagas-disponiveis-hoje-confira\/#google_vignette\" target=\"_blank\" rel=\"noopener\">oportunidades<\/a> de <a href=\"https:\/\/99empregos.com.br\/blog\/hortifruti-natural-da-terra-rede-tem-vagas-de-primeiro-emprego-confira\/\" target=\"_blank\" rel=\"noopener\">emprego<\/a> em diversos setores e para diferentes n\u00edveis educacionais, assegurando o sucesso cont\u00ednuo de seus projetos. Confira algumas das <a href=\"https:\/\/99empregos.com.br\/blog\/subway-rede-tem-vagas-em-todas-as-regioes-do-pais-confira-oportunidades\/\" target=\"_blank\" rel=\"noopener\">posi\u00e7\u00f5es<\/a> dispon\u00edveis atualmente:<\/p>\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"h-full\">\n<div class=\"react-scroll-to-bottom--css-jqcvd-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-jqcvd-1n7m0yu\">\n<div class=\"flex flex-col text-sm md:pb-9\">\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-33\" data-scroll-anchor=\"true\">\n<div class=\"py-2 juice:py-[18px] px-3 text-base md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-3 text-base juice:gap-4 juice:md:gap-5 juice:lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div class=\"pt-0.5 juice:pt-0\">\n<div class=\"gizmo-bot-avatar flex h-6 w-6 items-center justify-center overflow-hidden rounded-full juice:h-8 juice:w-8\">\n<ul>\n<li class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-6 w-6\">Supervisor de Manuten\u00e7\u00e3o Eletromec\u00e2nica &#8211; afirmativa para mulheres &#8211; S\u00e3o Jo\u00e3o da Barra\/RJ<\/li>\n<li>T\u00e9cnico de Mec\u00e2nica Especialista &#8211; S\u00e3o Jo\u00e3o da Barra\/RJ<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"w-full md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)] juice:w-full\">\n<div class=\"px-3 text-base md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-3 text-base juice:gap-4 juice:md:gap-5 juice:lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"relative flex h-full max-w-full flex-1 flex-col\">\n<div class=\"absolute bottom-full left-0 right-0 z-20\">\n<h2><strong>Sobre a Ferroport <\/strong><\/h2>\n<p>A empresa oferece um sal\u00e1rio compat\u00edvel com o mercado de trabalho e o colaborador pode contar com os seguintes benef\u00edcios: vale-transporte, vale-refei\u00e7\u00e3o, seguro de vida, assist\u00eancia m\u00e9dica e assist\u00eancia odontol\u00f3gica.<\/p>\n<h2><b>Saiba como concorrer as vagas dispon\u00edveis\u00a0<\/b><\/h2>\n<p>O processo para se candidatar as vagas da Ferroport \u00e9 simples, ao clicar nesse <a href=\"https:\/\/99empregos.com.br\/vaga\/ferroport-empresa-de-alta-relevancia-no-segmento-industrial-tem-vagas-confira\/\" target=\"_blank\" rel=\"noopener\">link<\/a>, voc\u00ea poder\u00e1 clicar em Candidatar que voc\u00ea ser\u00e1 redirecionado para a \u00e1rea Trabalhe Conosco da empresa. L\u00e1, voc\u00ea ter\u00e1 acesso as diversas vagas e, ao escolher a que se encaixa no seu perfil clique em: Ver descri\u00e7\u00e3o da vaga.<\/p>\n<p>Em seguida, certifique-se de preencher os pr\u00e9-requisitos. Depois \u00e9 s\u00f3 clicar em Inscreva-se e anexar o seu curr\u00edculo. Voc\u00ea pode ainda cadastrar o seu curr\u00edculo no banco de vagas caso n\u00e3o encontre uma vaga.<\/p>\n<\/div>\n<div class=\"flex w-full items-center\">\n<div class=\"overflow-hidden [&amp;:has(textarea:focus)]:border-token-border-xheavy [&amp;:has(textarea:focus)]:shadow-[0_2px_6px_rgba(0,0,0,.05)] flex flex-col w-full flex-grow relative border dark:text-white rounded-2xl bg-token-main-surface-primary border-token-border-medium\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Ferroport \u00e9 uma parceria 100% brasileira formada pela mineradora Anglo American e pela empresa de infraestrutura e log\u00edstica Prumo Log\u00edstica. Seu principal foco \u00e9 a opera\u00e7\u00e3o do terminal portu\u00e1rio de min\u00e9rio de ferro no Porto do A\u00e7u. Com uma equipe diversificada e altamente especializada, a empresa possui ampla experi\u00eancia em terminais portu\u00e1rios e utiliza [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":60111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1401,1402,2683],"class_list":["post-60110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas","tag-nivel-medio","tag-nivel-superior","tag-nivel-tecnico"],"_links":{"self":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/60110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=60110"}],"version-history":[{"count":0,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/posts\/60110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media\/60111"}],"wp:attachment":[{"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=60110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=60110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/99empregos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=60110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}